{"id":1227,"count":2,"description":"","link":"https:\/\/wenttrip.com.br\/it\/etichetta\/mappa-del-parco-mongolfiere\/","name":"Mappa del Parco delle Mongolfiere","slug":"mapa-do-parque-do-balonismo","taxonomy":"post_tag","meta":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Arquivo de Mapa do Parque do Balonismo - WentTrip<\/title>\n<meta name=\"description\" content=\"Mapa do Parque do Balonismo\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/wenttrip.com.br\/it\/etichetta\/mappa-del-parco-mongolfiere\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Arquivo de Mapa do Parque do Balonismo - WentTrip\" \/>\n<meta property=\"og:description\" content=\"Mapa do Parque do Balonismo\" \/>\n<meta property=\"og:url\" content=\"https:\/\/wenttrip.com.br\/it\/etichetta\/mappa-del-parco-mongolfiere\/\" \/>\n<meta property=\"og:site_name\" content=\"WentTrip\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:site\" content=\"@wenttrip\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"CollectionPage\",\"@id\":\"https:\\\/\\\/wenttrip.com.br\\\/it\\\/etichetta\\\/mappa-del-parco-mongolfiere\\\/\",\"url\":\"https:\\\/\\\/wenttrip.com.br\\\/it\\\/etichetta\\\/mappa-del-parco-mongolfiere\\\/\",\"name\":\"Arquivo de Mapa do Parque do Balonismo - WentTrip\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/wenttrip.com.br\\\/it\\\/#website\"},\"description\":\"Mapa do Parque do Balonismo\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/wenttrip.com.br\\\/it\\\/etichetta\\\/mappa-del-parco-mongolfiere\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/wenttrip.com.br\\\/it\\\/etichetta\\\/mappa-del-parco-mongolfiere\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"In\u00edcio\",\"item\":\"https:\\\/\\\/wenttrip.com.br\\\/it\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Mapa do Parque do Balonismo\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/wenttrip.com.br\\\/it\\\/#website\",\"url\":\"https:\\\/\\\/wenttrip.com.br\\\/it\\\/\",\"name\":\"WentTrip\",\"description\":\"O seu guia completo com muitas dicas de aventuras, lugares, alimenta\u00e7\u00e3o, hot\u00e9is.\",\"publisher\":{\"@id\":\"https:\\\/\\\/wenttrip.com.br\\\/it\\\/#\\\/schema\\\/person\\\/c0ff87b449a960037fdd1b024842fcf9\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/wenttrip.com.br\\\/it\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":[\"Person\",\"Organization\"],\"@id\":\"https:\\\/\\\/wenttrip.com.br\\\/it\\\/#\\\/schema\\\/person\\\/c0ff87b449a960037fdd1b024842fcf9\",\"name\":\"Fernanda Machado\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/wenttrip.com.br\\\/wp-content\\\/uploads\\\/2022\\\/08\\\/WentTrip-2.png\",\"url\":\"https:\\\/\\\/wenttrip.com.br\\\/wp-content\\\/uploads\\\/2022\\\/08\\\/WentTrip-2.png\",\"contentUrl\":\"https:\\\/\\\/wenttrip.com.br\\\/wp-content\\\/uploads\\\/2022\\\/08\\\/WentTrip-2.png\",\"width\":1000,\"height\":1000,\"caption\":\"Fernanda Machado\"},\"logo\":{\"@id\":\"https:\\\/\\\/wenttrip.com.br\\\/wp-content\\\/uploads\\\/2022\\\/08\\\/WentTrip-2.png\"},\"description\":\"Aprendi que a vida \u00e9 mais leve quando colocamos uma mochila nas costas junto com sonhos. Amo viajar! Tenho 34 anos, mam\u00e3e de 3 cachorros: A Pantufa, O mutley e o Mixuruca. Compartilhamos nossas experi\u00eancias por aqui, esperamos que gostem!\",\"sameAs\":[\"https:\\\/\\\/wenttrip.com.br\",\"https:\\\/\\\/m.facebook.com\\\/profile.php\",\"https:\\\/\\\/www.instagram.com\\\/wenttrip\\\/\",\"https:\\\/\\\/x.com\\\/https:\\\/\\\/twitter.com\\\/wenttrip\",\"https:\\\/\\\/www.youtube.com\\\/c\\\/WentTrip\\\/videos\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Arquivo de Mapa do Parque do Balonismo - WentTrip","description":"Mappa del Parco delle Mongolfiere","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/wenttrip.com.br\/it\/etichetta\/mappa-del-parco-mongolfiere\/","og_locale":"it_IT","og_type":"article","og_title":"Arquivo de Mapa do Parque do Balonismo - WentTrip","og_description":"Mapa do Parque do Balonismo","og_url":"https:\/\/wenttrip.com.br\/it\/etichetta\/mappa-del-parco-mongolfiere\/","og_site_name":"WentTrip","twitter_card":"summary_large_image","twitter_site":"@wenttrip","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"CollectionPage","@id":"https:\/\/wenttrip.com.br\/it\/etichetta\/mappa-del-parco-mongolfiere\/","url":"https:\/\/wenttrip.com.br\/it\/etichetta\/mappa-del-parco-mongolfiere\/","name":"Archivio delle mappe del parco in mongolfiera - WentTrip","isPartOf":{"@id":"https:\/\/wenttrip.com.br\/it\/#website"},"description":"Mappa del Parco delle Mongolfiere","breadcrumb":{"@id":"https:\/\/wenttrip.com.br\/it\/etichetta\/mappa-del-parco-mongolfiere\/#breadcrumb"},"inLanguage":"it-IT"},{"@type":"BreadcrumbList","@id":"https:\/\/wenttrip.com.br\/it\/etichetta\/mappa-del-parco-mongolfiere\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"In\u00edcio","item":"https:\/\/wenttrip.com.br\/it\/"},{"@type":"ListItem","position":2,"name":"Mapa do Parque do Balonismo"}]},{"@type":"WebSite","@id":"https:\/\/wenttrip.com.br\/it\/#website","url":"https:\/\/wenttrip.com.br\/it\/","name":"Andato in viaggio","description":"La tua guida completa con tanti consigli su avventure, luoghi, cibo, hotel.","publisher":{"@id":"https:\/\/wenttrip.com.br\/it\/#\/schema\/person\/c0ff87b449a960037fdd1b024842fcf9"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/wenttrip.com.br\/it\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":["Person","Organization"],"@id":"https:\/\/wenttrip.com.br\/it\/#\/schema\/person\/c0ff87b449a960037fdd1b024842fcf9","name":"Fernanda Macchado","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/wenttrip.com.br\/wp-content\/uploads\/2022\/08\/WentTrip-2.png","url":"https:\/\/wenttrip.com.br\/wp-content\/uploads\/2022\/08\/WentTrip-2.png","contentUrl":"https:\/\/wenttrip.com.br\/wp-content\/uploads\/2022\/08\/WentTrip-2.png","width":1000,"height":1000,"caption":"Fernanda Machado"},"logo":{"@id":"https:\/\/wenttrip.com.br\/wp-content\/uploads\/2022\/08\/WentTrip-2.png"},"description":"Ho imparato che la vita \u00e8 pi\u00f9 leggera quando ci mettiamo uno zaino in spalla insieme ai sogni. Amo viaggiare! Ho 34 anni, mamma di 3 cani: Pantufa, Mutley e Mixuruca. Condividiamo qui le nostre esperienze, speriamo vi piaccia!","sameAs":["https:\/\/wenttrip.com.br","https:\/\/m.facebook.com\/profile.php","https:\/\/www.instagram.com\/wenttrip\/","https:\/\/x.com\/https:\/\/twitter.com\/wenttrip","https:\/\/www.youtube.com\/c\/WentTrip\/videos"]}]}},"_links":{"self":[{"href":"https:\/\/wenttrip.com.br\/it\/wp-json\/wp\/v2\/tags\/1227","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/wenttrip.com.br\/it\/wp-json\/wp\/v2\/tags"}],"about":[{"href":"https:\/\/wenttrip.com.br\/it\/wp-json\/wp\/v2\/taxonomies\/post_tag"}],"wp:post_type":[{"href":"https:\/\/wenttrip.com.br\/it\/wp-json\/wp\/v2\/posts?tags=1227"}],"curies":[{"name":"parola chiave","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}