{"id":23504,"date":"2023-11-14T18:28:19","date_gmt":"2023-11-14T21:28:19","guid":{"rendered":"https:\/\/wenttrip.com.br\/?p=23504"},"modified":"2023-11-28T19:58:38","modified_gmt":"2023-11-28T22:58:38","slug":"a-lenha-pizzaria-e-restaurante-em-torres","status":"publish","type":"post","link":"https:\/\/wenttrip.com.br\/es\/brasil\/brasil-sul\/rio-grande-do-sul\/torres\/pizzeria-y-restaurante-al-lena-en-torres\/","title":{"rendered":"Pizzer\u00eda y Restaurante \u00c0 Lenha en Torres"},"content":{"rendered":"<div id=\"ez-toc-container\" class=\"ez-toc-v2_0_85 counter-hierarchy ez-toc-counter ez-toc-grey ez-toc-container-direction\">\n<div class=\"ez-toc-title-container\">\n<p class=\"ez-toc-title\" style=\"cursor:inherit\">\u00cdndice<\/p>\n<span class=\"ez-toc-title-toggle\"><a href=\"#\" class=\"ez-toc-pull-right ez-toc-btn ez-toc-btn-xs ez-toc-btn-default ez-toc-toggle\" aria-label=\"Alternar tabla de contenidos\"><span class=\"ez-toc-js-icon-con\"><span class=\"\"><span class=\"eztoc-hide\" style=\"display:none;\">palanca<\/span><span class=\"ez-toc-icon-toggle-span\"><svg style=\"fill: #999;color:#999\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" class=\"list-377408\" width=\"20px\" height=\"20px\" viewbox=\"0 0 24 24\" fill=\"none\"><path d=\"M6 6H4v2h2V6zm14 0H8v2h12V6zM4 11h2v2H4v-2zm16 0H8v2h12v-2zM4 16h2v2H4v-2zm16 0H8v2h12v-2z\" fill=\"currentColor\"><\/path><\/svg><svg style=\"fill: #999;color:#999\" class=\"arrow-unsorted-368013\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"10px\" height=\"10px\" viewbox=\"0 0 24 24\" version=\"1.2\" baseprofile=\"tiny\"><path d=\"M18.2 9.3l-6.2-6.3-6.2 6.3c-.2.2-.3.4-.3.7s.1.5.3.7c.2.2.4.3.7.3h11c.3 0 .5-.1.7-.3.2-.2.3-.5.3-.7s-.1-.5-.3-.7zM5.8 14.7l6.2 6.3 6.2-6.3c.2-.2.3-.5.3-.7s-.1-.5-.3-.7c-.2-.2-.4-.3-.7-.3h-11c-.3 0-.5.1-.7.3-.2.2-.3.5-.3.7s.1.5.3.7z\"\/><\/svg><\/span><\/span><\/span><\/a><\/span><\/div>\n<nav><ul class='ez-toc-list ez-toc-list-level-1' ><li class='ez-toc-page-1 ez-toc-heading-level-2'><a class=\"ez-toc-link ez-toc-heading-1\" href=\"https:\/\/wenttrip.com.br\/es\/brasil\/brasil-sul\/rio-grande-do-sul\/torres\/pizzeria-y-restaurante-al-lena-en-torres\/#Onde_fica_a_A_Lenha_Pizzaria_de_Torres\" >\u00bfD\u00f3nde est\u00e1 Pizzer\u00eda \u00c0 Lenha de Torres?<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-2'><a class=\"ez-toc-link ez-toc-heading-2\" href=\"https:\/\/wenttrip.com.br\/es\/brasil\/brasil-sul\/rio-grande-do-sul\/torres\/pizzeria-y-restaurante-al-lena-en-torres\/#Conheca_a_A_Lenha_Pizzaria_em_Torres\" >Descubre Pizzer\u00eda \u00c0 Lenha en Torres<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-2'><a class=\"ez-toc-link ez-toc-heading-3\" href=\"https:\/\/wenttrip.com.br\/es\/brasil\/brasil-sul\/rio-grande-do-sul\/torres\/pizzeria-y-restaurante-al-lena-en-torres\/#Horario_de_funcionamento_da_A_Lenha_Pizzaria\" >Horario de apertura para Pizzaria A Lenha<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-2'><a class=\"ez-toc-link ez-toc-heading-4\" href=\"https:\/\/wenttrip.com.br\/es\/brasil\/brasil-sul\/rio-grande-do-sul\/torres\/pizzeria-y-restaurante-al-lena-en-torres\/#Telefone_da_A_Lenha_Pizzaria_de_Torres\" >N\u00famero de tel\u00e9fono de \u00c0 Lenha Pizzer\u00eda de Torres<\/a><\/li><\/ul><\/nav><\/div>\n\n<p>La pizzer\u00eda \u00c0 Lenha se gan\u00f3 el coraz\u00f3n de todos, las pizzas se hornean en horno de le\u00f1a, dejando un toque a\u00fan m\u00e1s especial. Es una pizzer\u00eda refinada y moderna, es una gran opci\u00f3n para impresionar en una cena sofisticada, para celebrar un cumplea\u00f1os o para una cena de empresa. \u00a1Mira nuestros consejos sobre este lugar tan especial aqu\u00ed!<\/p>\n\n\n\n<p>Disfruta y descubre m\u00e1s sobre<strong>\u00a0<a href=\"https:\/\/wenttrip.com.br\/es\/brasil\/brasil-sul\/rio-grande-do-sul\/torres\/que-hacer-en-torres-rs-playas-y-lugares-turisticos\/\" target=\"_blank\" rel=\"noreferrer noopener\">Qu\u00e9 hacer en Torres \u2013 RS \u2013 Playas y lugares de inter\u00e9s<\/a><\/strong>\u00a0y si a\u00fan no lo has encontrado\u00a0<a href=\"https:\/\/wenttrip.com.br\/es\/brasil\/brasil-sul\/rio-grande-do-sul\/torres\/top-10-mejor-hotel-en-towers\/\" target=\"_blank\" rel=\"noreferrer noopener\"><strong>Hotel en Torres: los 10 mejores<\/strong><\/a>, \u00a1\u00c9chale un vistazo ahora!<\/p>\n\n\n\n<blockquote class=\"wp-block-quote is-layout-flow wp-block-quote-is-layout-flow\">\n<p><strong>Pero primero, haz tu reserva de hotel:<\/strong><\/p>\n\n\n\n<p>Creemos mucho en la excelencia de&nbsp;<strong><a href=\"https:\/\/www.booking.com\/index.html?aid=8010377\" target=\"_blank\" rel=\"noreferrer noopener\">Reserva&nbsp;<\/a><\/strong>\u00a1Tambi\u00e9n decidimos hacer nuestras reservas all\u00ed! La seguridad es primordial y el&nbsp;<strong><a href=\"https:\/\/www.booking.com\/index.html?aid=8010377\" target=\"_blank\" rel=\"noreferrer noopener\">Reserva<\/a><\/strong>&nbsp;ofrece una plataforma confiable, con sistemas de pago seguros y&nbsp;<strong>Comentarios reales de otros viajeros.<\/strong><\/p>\n\n\n\n<p>Reserva con&nbsp;<strong><a href=\"https:\/\/www.booking.com\/index.html?aid=8010377\" target=\"_blank\" rel=\"noreferrer noopener\">Reserva<\/a><\/strong>y disfrute de la tranquilidad de una experiencia de alquiler garantizada y confiable. \u00a1Tu viaje comienza con confianza y comodidad! \ud83c\udf10\ud83d\udd10 Recordando que el&nbsp;<strong>la cancelaci\u00f3n es gratuita<\/strong>\u00a1Haciendo a\u00fan m\u00e1s ventajoso hacer tus reservas lo antes posible!<\/p>\n<\/blockquote>\n\n\n\n<h2 class=\"wp-block-heading\"><span class=\"ez-toc-section\" id=\"Onde_fica_a_A_Lenha_Pizzaria_de_Torres\"><\/span>\u00bfD\u00f3nde est\u00e1 Pizzer\u00eda \u00c0 Lenha de Torres?<span class=\"ez-toc-section-end\"><\/span><\/h2>\n\n\n\n<p>Llegar a la pizzer\u00eda es s\u00faper f\u00e1cil, ya que est\u00e1 ubicada en primera l\u00ednea de mar en <strong>Avenida Beira Mar, 830<\/strong>.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\"><span class=\"ez-toc-section\" id=\"Conheca_a_A_Lenha_Pizzaria_em_Torres\"><\/span>Descubre Pizzer\u00eda \u00c0 Lenha en Torres<span class=\"ez-toc-section-end\"><\/span><\/h2>\n\n\n\n<p>Es una pizzer\u00eda refinada y moderna, es una gran opci\u00f3n para impresionar en una cena sofisticada, para celebrar un cumplea\u00f1os o para una cena de empresa. <\/p>\n\n\n\n<p>Durante el invierno las sillas se cubren con pieles y todo el ambiente est\u00e1 climatizado.<\/p>\n\n\n\n<p>Tienen una maravillosa y moderna carta, con opciones de pizzas, calzones, hamburguesas, bruschetta, filetes a la parmesana, mariscos, snacks, pastas (individuales), entrecot y una enorme carta de vinos, diferentes tipos de cervezas, jugos y refrescos. <\/p>\n\n\n\n<p>La opci\u00f3n es s\u00f3lo a la carta y es posible solicitar pedido tele.<\/p>\n\n\n\n<figure class=\"wp-block-image size-full is-resized\"><img decoding=\"async\" width=\"516\" height=\"645\" src=\"https:\/\/wenttrip.com.br\/wp-content\/uploads\/2023\/11\/image-1.png\" alt=\"Pizzer\u00eda a la Le\u00f1a \" class=\"wp-image-23507\" style=\"width:338px;height:auto\" srcset=\"https:\/\/wenttrip.com.br\/wp-content\/uploads\/2023\/11\/image-1.png 516w, https:\/\/wenttrip.com.br\/wp-content\/uploads\/2023\/11\/image-1-240x300.png 240w, https:\/\/wenttrip.com.br\/wp-content\/uploads\/2023\/11\/image-1-10x12.png 10w\" sizes=\"(max-width: 516px) 100vw, 516px\" \/><\/figure>\n\n\n\n<p>O <strong>valor <\/strong>de una <strong>pizza grande<\/strong> Cuesta alrededor de R$125.00, funciona bien <strong>3 personas <\/strong>y tiene 12 piezas con hasta 3 sabores. Una pizza mediana para <strong>2 personas<\/strong> Cuesta alrededor de R$100.00.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\"><span class=\"ez-toc-section\" id=\"Horario_de_funcionamento_da_A_Lenha_Pizzaria\"><\/span>Horario de apertura para Pizzaria A Lenha <span class=\"ez-toc-section-end\"><\/span><\/h2>\n\n\n\n<p><strong>Abierto<\/strong> diariamente de lunes a viernes de 6:30 pm a 11:30 pm. Hacia <strong>s\u00e1bados y domingos<\/strong> Est\u00e1 abierto: 11:30 am a 2:30 pm, 6:30 pm a 11:30 pm.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\"><span class=\"ez-toc-section\" id=\"Telefone_da_A_Lenha_Pizzaria_de_Torres\"><\/span>N\u00famero de tel\u00e9fono de \u00c0 Lenha Pizzer\u00eda de Torres<span class=\"ez-toc-section-end\"><\/span><\/h2>\n\n\n\n<p>Haga una reserva a trav\u00e9s de <strong>Qu\u00e9:<\/strong>&nbsp;(51) 98028-0795, es una gran opci\u00f3n para quienes prefieren quedarse en casa y pedir un delivery. Por WhatsApp te enviar\u00e1n el men\u00fa.<\/p>\n\n\n\n<figure class=\"wp-block-image size-large\"><img decoding=\"async\" width=\"800\" height=\"341\" src=\"https:\/\/wenttrip.com.br\/wp-content\/uploads\/2023\/11\/cardapio-pizzaria-a-lenha-800x341.png\" alt=\"Carta de Lenha Pizzeria de Torres\" class=\"wp-image-23510\" srcset=\"https:\/\/wenttrip.com.br\/wp-content\/uploads\/2023\/11\/cardapio-pizzaria-a-lenha-800x341.png 800w, https:\/\/wenttrip.com.br\/wp-content\/uploads\/2023\/11\/cardapio-pizzaria-a-lenha-300x128.png 300w, https:\/\/wenttrip.com.br\/wp-content\/uploads\/2023\/11\/cardapio-pizzaria-a-lenha-768x327.png 768w, https:\/\/wenttrip.com.br\/wp-content\/uploads\/2023\/11\/cardapio-pizzaria-a-lenha-18x8.png 18w, https:\/\/wenttrip.com.br\/wp-content\/uploads\/2023\/11\/cardapio-pizzaria-a-lenha.png 1084w\" sizes=\"(max-width: 800px) 100vw, 800px\" \/><\/figure>\n\n\n\n<p>Disfruta y descubre m\u00e1s sobre<strong>&nbsp;<a href=\"https:\/\/wenttrip.com.br\/es\/brasil\/brasil-sul\/rio-grande-do-sul\/torres\/que-hacer-en-torres-rs-playas-y-lugares-turisticos\/\" target=\"_blank\" rel=\"noreferrer noopener\">Qu\u00e9 hacer en Torres \u2013 RS \u2013 Playas y lugares de inter\u00e9s<\/a><\/strong>&nbsp;y si a\u00fan no lo has encontrado&nbsp;<a href=\"https:\/\/wenttrip.com.br\/es\/brasil\/brasil-sul\/rio-grande-do-sul\/torres\/top-10-mejor-hotel-en-towers\/\" target=\"_blank\" rel=\"noreferrer noopener\"><strong>Hotel en Torres: los 10 mejores<\/strong><\/a>, \u00a1\u00c9chale un vistazo ahora!<\/p>","protected":false},"excerpt":{"rendered":"<p>La pizzer\u00eda \u00c0 Lenha se gan\u00f3 el coraz\u00f3n de todos, las pizzas se hornean en horno de le\u00f1a, dejando un toque a\u00fan m\u00e1s especial. Es una pizzer\u00eda refinada y moderna, es una gran opci\u00f3n para impresionar en una cena sofisticada, para celebrar un cumplea\u00f1os o para una cena de empresa. Consulta nuestros consejos aqu\u00ed...&nbsp;<a href=\"https:\/\/wenttrip.com.br\/es\/brasil\/brasil-sul\/rio-grande-do-sul\/torres\/pizzeria-y-restaurante-al-lena-en-torres\/\" rel=\"bookmark\">leer m\u00e1s &quot;<span class=\"screen-reader-text\">Pizzer\u00eda y Restaurante \u00c0 Lenha en Torres<\/span><\/a><\/p>","protected":false},"author":1,"featured_media":23514,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"neve_meta_sidebar":"","neve_meta_container":"","neve_meta_enable_content_width":"","neve_meta_content_width":0,"neve_meta_title_alignment":"","neve_meta_author_avatar":"","neve_post_elements_order":"","neve_meta_disable_header":"","neve_meta_disable_footer":"","neve_meta_disable_title":"","footnotes":""},"categories":[1720],"tags":[4546,4545,4544,28],"class_list":["post-23504","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-torres","tag-a-lenha-pizzaria","tag-dicas-de-pizzaria","tag-pizzaria-em-torres","tag-torres-rs"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>\u00c0 Lenha Pizzaria e Restaurante em Torres - WentTrip<\/title>\n<meta name=\"description\" content=\"A pizzaria \u00c0 Lenha ganhou o cora\u00e7\u00e3o de todos, as pizzas s\u00e3o assadas no forno \u00e0 lenha, deixando um toque ainda mais especial. Ela \u00e9 uma requintada e moderna pizzaria, \u00e9 uma \u00f3tima op\u00e7\u00e3o para impressionar em um jantar sofisticado, para comemorar um anivers\u00e1rio ou para um jantar de neg\u00f3cios. Confira aqui as nossas dicas sobre esse lugar especial!\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/wenttrip.com.br\/es\/brasil\/brasil-sul\/rio-grande-do-sul\/torres\/pizzeria-y-restaurante-al-lena-en-torres\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"\u00c0 Lenha Pizzaria e Restaurante em Torres - WentTrip\" \/>\n<meta property=\"og:description\" content=\"A pizzaria \u00c0 Lenha ganhou o cora\u00e7\u00e3o de todos, as pizzas s\u00e3o assadas no forno \u00e0 lenha, deixando um toque ainda mais especial. Ela \u00e9 uma requintada e moderna pizzaria, \u00e9 uma \u00f3tima op\u00e7\u00e3o para impressionar em um jantar sofisticado, para comemorar um anivers\u00e1rio ou para um jantar de neg\u00f3cios. Confira aqui as nossas dicas sobre esse lugar especial!\" \/>\n<meta property=\"og:url\" content=\"https:\/\/wenttrip.com.br\/es\/brasil\/brasil-sul\/rio-grande-do-sul\/torres\/pizzeria-y-restaurante-al-lena-en-torres\/\" \/>\n<meta property=\"og:site_name\" content=\"WentTrip\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/m.facebook.com\/profile.php\" \/>\n<meta property=\"article:author\" content=\"https:\/\/m.facebook.com\/profile.php\" \/>\n<meta property=\"article:published_time\" content=\"2023-11-14T21:28:19+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2023-11-28T22:58:38+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/wenttrip.com.br\/wp-content\/uploads\/2023\/11\/a-lenha-pizzaria.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1200\" \/>\n\t<meta property=\"og:image:height\" content=\"800\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Fernanda Machado\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@https:\/\/twitter.com\/wenttrip\" \/>\n<meta name=\"twitter:site\" content=\"@wenttrip\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Fernanda Machado\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/wenttrip.com.br\\\/es\\\/brasil\\\/brasil-sul\\\/rio-grande-do-sul\\\/torres\\\/pizzeria-y-restaurante-al-lena-en-torres\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/wenttrip.com.br\\\/es\\\/brasil\\\/brasil-sul\\\/rio-grande-do-sul\\\/torres\\\/pizzeria-y-restaurante-al-lena-en-torres\\\/\"},\"author\":{\"name\":\"Fernanda Machado\",\"@id\":\"https:\\\/\\\/wenttrip.com.br\\\/es\\\/#\\\/schema\\\/person\\\/c0ff87b449a960037fdd1b024842fcf9\"},\"headline\":\"\u00c0 Lenha Pizzaria e Restaurante em Torres\",\"datePublished\":\"2023-11-14T21:28:19+00:00\",\"dateModified\":\"2023-11-28T22:58:38+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/wenttrip.com.br\\\/es\\\/brasil\\\/brasil-sul\\\/rio-grande-do-sul\\\/torres\\\/pizzeria-y-restaurante-al-lena-en-torres\\\/\"},\"wordCount\":460,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/wenttrip.com.br\\\/es\\\/#\\\/schema\\\/person\\\/c0ff87b449a960037fdd1b024842fcf9\"},\"image\":{\"@id\":\"https:\\\/\\\/wenttrip.com.br\\\/es\\\/brasil\\\/brasil-sul\\\/rio-grande-do-sul\\\/torres\\\/pizzeria-y-restaurante-al-lena-en-torres\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/wenttrip.com.br\\\/wp-content\\\/uploads\\\/2023\\\/11\\\/a-lenha-pizzaria.jpg\",\"keywords\":[\"a lenha pizzaria\",\"dicas de pizzaria\",\"pizzaria em torres\",\"Torres rs\"],\"articleSection\":[\"Torres\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/wenttrip.com.br\\\/es\\\/brasil\\\/brasil-sul\\\/rio-grande-do-sul\\\/torres\\\/pizzeria-y-restaurante-al-lena-en-torres\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/wenttrip.com.br\\\/es\\\/brasil\\\/brasil-sul\\\/rio-grande-do-sul\\\/torres\\\/pizzeria-y-restaurante-al-lena-en-torres\\\/\",\"url\":\"https:\\\/\\\/wenttrip.com.br\\\/es\\\/brasil\\\/brasil-sul\\\/rio-grande-do-sul\\\/torres\\\/pizzeria-y-restaurante-al-lena-en-torres\\\/\",\"name\":\"\u00c0 Lenha Pizzaria e Restaurante em Torres - WentTrip\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/wenttrip.com.br\\\/es\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/wenttrip.com.br\\\/es\\\/brasil\\\/brasil-sul\\\/rio-grande-do-sul\\\/torres\\\/pizzeria-y-restaurante-al-lena-en-torres\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/wenttrip.com.br\\\/es\\\/brasil\\\/brasil-sul\\\/rio-grande-do-sul\\\/torres\\\/pizzeria-y-restaurante-al-lena-en-torres\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/wenttrip.com.br\\\/wp-content\\\/uploads\\\/2023\\\/11\\\/a-lenha-pizzaria.jpg\",\"datePublished\":\"2023-11-14T21:28:19+00:00\",\"dateModified\":\"2023-11-28T22:58:38+00:00\",\"description\":\"A pizzaria \u00c0 Lenha ganhou o cora\u00e7\u00e3o de todos, as pizzas s\u00e3o assadas no forno \u00e0 lenha, deixando um toque ainda mais especial. Ela \u00e9 uma requintada e moderna pizzaria, \u00e9 uma \u00f3tima op\u00e7\u00e3o para impressionar em um jantar sofisticado, para comemorar um anivers\u00e1rio ou para um jantar de neg\u00f3cios. Confira aqui as nossas dicas sobre esse lugar especial!\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/wenttrip.com.br\\\/es\\\/brasil\\\/brasil-sul\\\/rio-grande-do-sul\\\/torres\\\/pizzeria-y-restaurante-al-lena-en-torres\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/wenttrip.com.br\\\/es\\\/brasil\\\/brasil-sul\\\/rio-grande-do-sul\\\/torres\\\/pizzeria-y-restaurante-al-lena-en-torres\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/wenttrip.com.br\\\/es\\\/brasil\\\/brasil-sul\\\/rio-grande-do-sul\\\/torres\\\/pizzeria-y-restaurante-al-lena-en-torres\\\/#primaryimage\",\"url\":\"https:\\\/\\\/wenttrip.com.br\\\/wp-content\\\/uploads\\\/2023\\\/11\\\/a-lenha-pizzaria.jpg\",\"contentUrl\":\"https:\\\/\\\/wenttrip.com.br\\\/wp-content\\\/uploads\\\/2023\\\/11\\\/a-lenha-pizzaria.jpg\",\"width\":1200,\"height\":800,\"caption\":\"a lenha pizzaria em Torres\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/wenttrip.com.br\\\/es\\\/brasil\\\/brasil-sul\\\/rio-grande-do-sul\\\/torres\\\/pizzeria-y-restaurante-al-lena-en-torres\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"In\u00edcio\",\"item\":\"https:\\\/\\\/wenttrip.com.br\\\/es\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"\u00c0 Lenha Pizzaria e Restaurante em Torres\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/wenttrip.com.br\\\/es\\\/#website\",\"url\":\"https:\\\/\\\/wenttrip.com.br\\\/es\\\/\",\"name\":\"WentTrip\",\"description\":\"O seu guia completo com muitas dicas de aventuras, lugares, alimenta\u00e7\u00e3o, hot\u00e9is.\",\"publisher\":{\"@id\":\"https:\\\/\\\/wenttrip.com.br\\\/es\\\/#\\\/schema\\\/person\\\/c0ff87b449a960037fdd1b024842fcf9\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/wenttrip.com.br\\\/es\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":[\"Person\",\"Organization\"],\"@id\":\"https:\\\/\\\/wenttrip.com.br\\\/es\\\/#\\\/schema\\\/person\\\/c0ff87b449a960037fdd1b024842fcf9\",\"name\":\"Fernanda Machado\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/wenttrip.com.br\\\/wp-content\\\/uploads\\\/2022\\\/08\\\/WentTrip-2.png\",\"url\":\"https:\\\/\\\/wenttrip.com.br\\\/wp-content\\\/uploads\\\/2022\\\/08\\\/WentTrip-2.png\",\"contentUrl\":\"https:\\\/\\\/wenttrip.com.br\\\/wp-content\\\/uploads\\\/2022\\\/08\\\/WentTrip-2.png\",\"width\":1000,\"height\":1000,\"caption\":\"Fernanda Machado\"},\"logo\":{\"@id\":\"https:\\\/\\\/wenttrip.com.br\\\/wp-content\\\/uploads\\\/2022\\\/08\\\/WentTrip-2.png\"},\"description\":\"Aprendi que a vida \u00e9 mais leve quando colocamos uma mochila nas costas junto com sonhos. Amo viajar! Tenho 34 anos, mam\u00e3e de 3 cachorros: A Pantufa, O mutley e o Mixuruca. Compartilhamos nossas experi\u00eancias por aqui, esperamos que gostem!\",\"sameAs\":[\"https:\\\/\\\/wenttrip.com.br\",\"https:\\\/\\\/m.facebook.com\\\/profile.php\",\"https:\\\/\\\/www.instagram.com\\\/wenttrip\\\/\",\"https:\\\/\\\/x.com\\\/https:\\\/\\\/twitter.com\\\/wenttrip\",\"https:\\\/\\\/www.youtube.com\\\/c\\\/WentTrip\\\/videos\"],\"url\":\"https:\\\/\\\/wenttrip.com.br\\\/es\\\/author\\\/admin\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"\u00c0 Lenha Pizzer\u00eda y Restaurante en Torres - WentTrip","description":"La pizzer\u00eda \u00c0 Lenha se gan\u00f3 el coraz\u00f3n de todos, las pizzas se hornean en horno de le\u00f1a, dejando un toque a\u00fan m\u00e1s especial. Es una pizzer\u00eda refinada y moderna, es una gran opci\u00f3n para impresionar en una cena sofisticada, para celebrar un cumplea\u00f1os o para una cena de empresa. \u00a1Mira nuestros consejos sobre este lugar tan especial aqu\u00ed!","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/wenttrip.com.br\/es\/brasil\/brasil-sul\/rio-grande-do-sul\/torres\/pizzeria-y-restaurante-al-lena-en-torres\/","og_locale":"es_ES","og_type":"article","og_title":"\u00c0 Lenha Pizzaria e Restaurante em Torres - WentTrip","og_description":"A pizzaria \u00c0 Lenha ganhou o cora\u00e7\u00e3o de todos, as pizzas s\u00e3o assadas no forno \u00e0 lenha, deixando um toque ainda mais especial. Ela \u00e9 uma requintada e moderna pizzaria, \u00e9 uma \u00f3tima op\u00e7\u00e3o para impressionar em um jantar sofisticado, para comemorar um anivers\u00e1rio ou para um jantar de neg\u00f3cios. Confira aqui as nossas dicas sobre esse lugar especial!","og_url":"https:\/\/wenttrip.com.br\/es\/brasil\/brasil-sul\/rio-grande-do-sul\/torres\/pizzeria-y-restaurante-al-lena-en-torres\/","og_site_name":"WentTrip","article_publisher":"https:\/\/m.facebook.com\/profile.php","article_author":"https:\/\/m.facebook.com\/profile.php","article_published_time":"2023-11-14T21:28:19+00:00","article_modified_time":"2023-11-28T22:58:38+00:00","og_image":[{"width":1200,"height":800,"url":"https:\/\/wenttrip.com.br\/wp-content\/uploads\/2023\/11\/a-lenha-pizzaria.jpg","type":"image\/jpeg"}],"author":"Fernanda Machado","twitter_card":"summary_large_image","twitter_creator":"@https:\/\/twitter.com\/wenttrip","twitter_site":"@wenttrip","twitter_misc":{"Escrito por":"Fernanda Machado","Tiempo de lectura":"3 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/wenttrip.com.br\/es\/brasil\/brasil-sul\/rio-grande-do-sul\/torres\/pizzeria-y-restaurante-al-lena-en-torres\/#article","isPartOf":{"@id":"https:\/\/wenttrip.com.br\/es\/brasil\/brasil-sul\/rio-grande-do-sul\/torres\/pizzeria-y-restaurante-al-lena-en-torres\/"},"author":{"name":"Fernanda Machado","@id":"https:\/\/wenttrip.com.br\/es\/#\/schema\/person\/c0ff87b449a960037fdd1b024842fcf9"},"headline":"\u00c0 Lenha Pizzaria e Restaurante em Torres","datePublished":"2023-11-14T21:28:19+00:00","dateModified":"2023-11-28T22:58:38+00:00","mainEntityOfPage":{"@id":"https:\/\/wenttrip.com.br\/es\/brasil\/brasil-sul\/rio-grande-do-sul\/torres\/pizzeria-y-restaurante-al-lena-en-torres\/"},"wordCount":460,"commentCount":0,"publisher":{"@id":"https:\/\/wenttrip.com.br\/es\/#\/schema\/person\/c0ff87b449a960037fdd1b024842fcf9"},"image":{"@id":"https:\/\/wenttrip.com.br\/es\/brasil\/brasil-sul\/rio-grande-do-sul\/torres\/pizzeria-y-restaurante-al-lena-en-torres\/#primaryimage"},"thumbnailUrl":"https:\/\/wenttrip.com.br\/wp-content\/uploads\/2023\/11\/a-lenha-pizzaria.jpg","keywords":["a lenha pizzaria","dicas de pizzaria","pizzaria em torres","Torres rs"],"articleSection":["Torres"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/wenttrip.com.br\/es\/brasil\/brasil-sul\/rio-grande-do-sul\/torres\/pizzeria-y-restaurante-al-lena-en-torres\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/wenttrip.com.br\/es\/brasil\/brasil-sul\/rio-grande-do-sul\/torres\/pizzeria-y-restaurante-al-lena-en-torres\/","url":"https:\/\/wenttrip.com.br\/es\/brasil\/brasil-sul\/rio-grande-do-sul\/torres\/pizzeria-y-restaurante-al-lena-en-torres\/","name":"\u00c0 Lenha Pizzer\u00eda y Restaurante en Torres - WentTrip","isPartOf":{"@id":"https:\/\/wenttrip.com.br\/es\/#website"},"primaryImageOfPage":{"@id":"https:\/\/wenttrip.com.br\/es\/brasil\/brasil-sul\/rio-grande-do-sul\/torres\/pizzeria-y-restaurante-al-lena-en-torres\/#primaryimage"},"image":{"@id":"https:\/\/wenttrip.com.br\/es\/brasil\/brasil-sul\/rio-grande-do-sul\/torres\/pizzeria-y-restaurante-al-lena-en-torres\/#primaryimage"},"thumbnailUrl":"https:\/\/wenttrip.com.br\/wp-content\/uploads\/2023\/11\/a-lenha-pizzaria.jpg","datePublished":"2023-11-14T21:28:19+00:00","dateModified":"2023-11-28T22:58:38+00:00","description":"La pizzer\u00eda \u00c0 Lenha se gan\u00f3 el coraz\u00f3n de todos, las pizzas se hornean en horno de le\u00f1a, dejando un toque a\u00fan m\u00e1s especial. Es una pizzer\u00eda refinada y moderna, es una gran opci\u00f3n para impresionar en una cena sofisticada, para celebrar un cumplea\u00f1os o para una cena de empresa. \u00a1Mira nuestros consejos sobre este lugar tan especial aqu\u00ed!","breadcrumb":{"@id":"https:\/\/wenttrip.com.br\/es\/brasil\/brasil-sul\/rio-grande-do-sul\/torres\/pizzeria-y-restaurante-al-lena-en-torres\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/wenttrip.com.br\/es\/brasil\/brasil-sul\/rio-grande-do-sul\/torres\/pizzeria-y-restaurante-al-lena-en-torres\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/wenttrip.com.br\/es\/brasil\/brasil-sul\/rio-grande-do-sul\/torres\/pizzeria-y-restaurante-al-lena-en-torres\/#primaryimage","url":"https:\/\/wenttrip.com.br\/wp-content\/uploads\/2023\/11\/a-lenha-pizzaria.jpg","contentUrl":"https:\/\/wenttrip.com.br\/wp-content\/uploads\/2023\/11\/a-lenha-pizzaria.jpg","width":1200,"height":800,"caption":"a lenha pizzaria em Torres"},{"@type":"BreadcrumbList","@id":"https:\/\/wenttrip.com.br\/es\/brasil\/brasil-sul\/rio-grande-do-sul\/torres\/pizzeria-y-restaurante-al-lena-en-torres\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"In\u00edcio","item":"https:\/\/wenttrip.com.br\/es\/"},{"@type":"ListItem","position":2,"name":"\u00c0 Lenha Pizzaria e Restaurante em Torres"}]},{"@type":"WebSite","@id":"https:\/\/wenttrip.com.br\/es\/#website","url":"https:\/\/wenttrip.com.br\/es\/","name":"fuimos de viaje","description":"Tu gu\u00eda completa con muchos consejos sobre aventuras, lugares, comida, hoteles.","publisher":{"@id":"https:\/\/wenttrip.com.br\/es\/#\/schema\/person\/c0ff87b449a960037fdd1b024842fcf9"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/wenttrip.com.br\/es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":["Person","Organization"],"@id":"https:\/\/wenttrip.com.br\/es\/#\/schema\/person\/c0ff87b449a960037fdd1b024842fcf9","name":"Fernanda Machado","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/wenttrip.com.br\/wp-content\/uploads\/2022\/08\/WentTrip-2.png","url":"https:\/\/wenttrip.com.br\/wp-content\/uploads\/2022\/08\/WentTrip-2.png","contentUrl":"https:\/\/wenttrip.com.br\/wp-content\/uploads\/2022\/08\/WentTrip-2.png","width":1000,"height":1000,"caption":"Fernanda Machado"},"logo":{"@id":"https:\/\/wenttrip.com.br\/wp-content\/uploads\/2022\/08\/WentTrip-2.png"},"description":"Aprend\u00ed que la vida es m\u00e1s ligera cuando nos ponemos una mochila a la espalda junto con los sue\u00f1os. \u00a1Amo viajar! Tengo 34 a\u00f1os, madre de 3 perros: Pantufa, Mutley y Mixuruca. Compartimos aqu\u00ed nuestras experiencias, \u00a1esperamos que os guste!","sameAs":["https:\/\/wenttrip.com.br","https:\/\/m.facebook.com\/profile.php","https:\/\/www.instagram.com\/wenttrip\/","https:\/\/x.com\/https:\/\/twitter.com\/wenttrip","https:\/\/www.youtube.com\/c\/WentTrip\/videos"],"url":"https:\/\/wenttrip.com.br\/es\/author\/admin\/"}]}},"_links":{"self":[{"href":"https:\/\/wenttrip.com.br\/es\/wp-json\/wp\/v2\/posts\/23504","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/wenttrip.com.br\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/wenttrip.com.br\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/wenttrip.com.br\/es\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/wenttrip.com.br\/es\/wp-json\/wp\/v2\/comments?post=23504"}],"version-history":[{"count":0,"href":"https:\/\/wenttrip.com.br\/es\/wp-json\/wp\/v2\/posts\/23504\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/wenttrip.com.br\/es\/wp-json\/wp\/v2\/media\/23514"}],"wp:attachment":[{"href":"https:\/\/wenttrip.com.br\/es\/wp-json\/wp\/v2\/media?parent=23504"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/wenttrip.com.br\/es\/wp-json\/wp\/v2\/categories?post=23504"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/wenttrip.com.br\/es\/wp-json\/wp\/v2\/tags?post=23504"}],"curies":[{"name":"gracias","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}