{"id":4205,"date":"2022-05-03T12:21:49","date_gmt":"2022-05-03T12:21:49","guid":{"rendered":"https:\/\/wenttrip.com.br\/?p=4205"},"modified":"2022-07-11T11:15:11","modified_gmt":"2022-07-11T11:15:11","slug":"alabama-estados-unidos-das-americas","status":"publish","type":"post","link":"https:\/\/wenttrip.com.br\/en\/united-states\/alabama\/alabama-united-states-of-americas\/","title":{"rendered":"Alabama \u2013 United States of America"},"content":{"rendered":"<div id=\"ez-toc-container\" class=\"ez-toc-v2_0_85 counter-hierarchy ez-toc-counter ez-toc-grey ez-toc-container-direction\">\n<div class=\"ez-toc-title-container\">\n<p class=\"ez-toc-title\" style=\"cursor:inherit\">Index<\/p>\n<span class=\"ez-toc-title-toggle\"><a href=\"#\" class=\"ez-toc-pull-right ez-toc-btn ez-toc-btn-xs ez-toc-btn-default ez-toc-toggle\" aria-label=\"Toggle Table of Content\"><span class=\"ez-toc-js-icon-con\"><span class=\"\"><span class=\"eztoc-hide\" style=\"display:none;\">toggle<\/span><span class=\"ez-toc-icon-toggle-span\"><svg style=\"fill: #999;color:#999\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" class=\"list-377408\" width=\"20px\" height=\"20px\" viewbox=\"0 0 24 24\" fill=\"none\"><path d=\"M6 6H4v2h2V6zm14 0H8v2h12V6zM4 11h2v2H4v-2zm16 0H8v2h12v-2zM4 16h2v2H4v-2zm16 0H8v2h12v-2z\" fill=\"currentColor\"><\/path><\/svg><svg style=\"fill: #999;color:#999\" class=\"arrow-unsorted-368013\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"10px\" height=\"10px\" viewbox=\"0 0 24 24\" version=\"1.2\" baseprofile=\"tiny\"><path d=\"M18.2 9.3l-6.2-6.3-6.2 6.3c-.2.2-.3.4-.3.7s.1.5.3.7c.2.2.4.3.7.3h11c.3 0 .5-.1.7-.3.2-.2.3-.5.3-.7s-.1-.5-.3-.7zM5.8 14.7l6.2 6.3 6.2-6.3c.2-.2.3-.5.3-.7s-.1-.5-.3-.7c-.2-.2-.4-.3-.7-.3h-11c-.3 0-.5.1-.7.3-.2.2-.3.5-.3.7s.1.5.3.7z\"\/><\/svg><\/span><\/span><\/span><\/a><\/span><\/div>\n<nav><ul class='ez-toc-list ez-toc-list-level-1' ><li class='ez-toc-page-1 ez-toc-heading-level-2'><a class=\"ez-toc-link ez-toc-heading-1\" href=\"https:\/\/wenttrip.com.br\/en\/united-states\/alabama\/alabama-united-states-of-americas\/#Curiosidades_sobre_Alabama\" >facts about Alabama<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-2'><a class=\"ez-toc-link ez-toc-heading-2\" href=\"https:\/\/wenttrip.com.br\/en\/united-states\/alabama\/alabama-united-states-of-americas\/#Pontos_turisticos_de_Alabama\" >Alabama tourist attractions<\/a><ul class='ez-toc-list-level-3' ><li class='ez-toc-heading-level-3'><a class=\"ez-toc-link ez-toc-heading-3\" href=\"https:\/\/wenttrip.com.br\/en\/united-states\/alabama\/alabama-united-states-of-americas\/#US_Space_Rocket_Center\" >US Space &amp; Rocket Center<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-3'><a class=\"ez-toc-link ez-toc-heading-4\" href=\"https:\/\/wenttrip.com.br\/en\/united-states\/alabama\/alabama-united-states-of-americas\/#Reserva_Nacional_Little_River_Canyon\" >Little River Canyon National Reserve<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-3'><a class=\"ez-toc-link ez-toc-heading-5\" href=\"https:\/\/wenttrip.com.br\/en\/united-states\/alabama\/alabama-united-states-of-americas\/#Parque_Estadual_DeSoto\" >DeSoto State Park<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-3'><a class=\"ez-toc-link ez-toc-heading-6\" href=\"https:\/\/wenttrip.com.br\/en\/united-states\/alabama\/alabama-united-states-of-americas\/#Monumento_Nacional_Freedom_Riders\" >Freedom Riders National Monument<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-3'><a class=\"ez-toc-link ez-toc-heading-7\" href=\"https:\/\/wenttrip.com.br\/en\/united-states\/alabama\/alabama-united-states-of-americas\/#Riverfront_Park\" >Riverfront Park<\/a><ul class='ez-toc-list-level-4' ><li class='ez-toc-heading-level-4'><a class=\"ez-toc-link ez-toc-heading-8\" href=\"https:\/\/wenttrip.com.br\/en\/united-states\/alabama\/alabama-united-states-of-americas\/#Alabama_%E2%80%93_Estados_Unidos_das_Americas\" >Alabama \u2013 United States of America<\/a><\/li><\/ul><\/li><\/ul><\/li><\/ul><\/nav><\/div>\n\n<p>Discover here in this post everything about Alabama \u2013 United States of America, full of history, culture, tourist attractions and fun.<\/p>\n\n\n\n<p><\/p>\n\n\n\n<h2 class=\"wp-block-heading\"><span class=\"ez-toc-section\" id=\"Curiosidades_sobre_Alabama\"><\/span><strong>facts about Alabama<\/strong><span class=\"ez-toc-section-end\"><\/span><\/h2>\n\n\n\n<figure class=\"wp-block-image size-large is-resized\"><img decoding=\"async\" src=\"https:\/\/wenttrip.com.br\/wp-content\/uploads\/2022\/05\/00a-promo-image-birmingham-alabama-travel-guide-1024x768.webp\" alt=\"\" class=\"wp-image-4208\" width=\"664\" height=\"498\" srcset=\"https:\/\/wenttrip.com.br\/wp-content\/uploads\/2022\/05\/00a-promo-image-birmingham-alabama-travel-guide-1024x768.webp 1024w, https:\/\/wenttrip.com.br\/wp-content\/uploads\/2022\/05\/00a-promo-image-birmingham-alabama-travel-guide-300x225.webp 300w, https:\/\/wenttrip.com.br\/wp-content\/uploads\/2022\/05\/00a-promo-image-birmingham-alabama-travel-guide-768x576.webp 768w, https:\/\/wenttrip.com.br\/wp-content\/uploads\/2022\/05\/00a-promo-image-birmingham-alabama-travel-guide-1536x1152.webp 1536w, https:\/\/wenttrip.com.br\/wp-content\/uploads\/2022\/05\/00a-promo-image-birmingham-alabama-travel-guide-389x292.webp 389w, https:\/\/wenttrip.com.br\/wp-content\/uploads\/2022\/05\/00a-promo-image-birmingham-alabama-travel-guide.webp 2000w\" sizes=\"(max-width: 664px) 100vw, 664px\" \/><\/figure>\n\n\n\n<p>Considered the 30th largest state by area and the 24th most populous in the US, it has about 5 million inhabitants.<\/p>\n\n\n\n<p>It is located in the southeastern region of the country, its capital is <strong>Montgomery.<\/strong><\/p>\n\n\n\n<p><strong>the musical style<\/strong>: blues, country and jazz is present in all bars and restaurants, gospel is the charm that enchants the church choirs and which today is a world reference.<\/p>\n\n\n\n<p>??<strong>Sweet Home Alabama<\/strong>\u201d is a famous song by the band Lynyrd Skynyrd, known worldwide. We cannot forget the group The Rolling Stones, who went to the state to consolidate their musical career.<\/p>\n\n\n\n<figure class=\"wp-block-image size-full is-resized\"><img decoding=\"async\" src=\"https:\/\/wenttrip.com.br\/wp-content\/uploads\/2022\/05\/550x794.jpg\" alt=\"sweet home alabama\" class=\"wp-image-4209\" width=\"346\" height=\"499\" srcset=\"https:\/\/wenttrip.com.br\/wp-content\/uploads\/2022\/05\/550x794.jpg 550w, https:\/\/wenttrip.com.br\/wp-content\/uploads\/2022\/05\/550x794-208x300.jpg 208w\" sizes=\"(max-width: 346px) 100vw, 346px\" \/><\/figure>\n\n\n\n<p>Music really rocks this state! <\/p>\n\n\n\n<p>The state&#039;s cuisine is not left out, being considered one of the best in America! With seafood dishes, straight from the Gulf of Mexico to the main local delicacy: <strong>pecan pie.<\/strong><\/p>\n\n\n\n<figure class=\"wp-block-image size-full is-resized\"><img decoding=\"async\" src=\"https:\/\/wenttrip.com.br\/wp-content\/uploads\/2022\/05\/pecan-pie.jpg\" alt=\"pecan pie.\" class=\"wp-image-4210\" width=\"651\" height=\"434\" srcset=\"https:\/\/wenttrip.com.br\/wp-content\/uploads\/2022\/05\/pecan-pie.jpg 1024w, https:\/\/wenttrip.com.br\/wp-content\/uploads\/2022\/05\/pecan-pie-300x200.jpg 300w, https:\/\/wenttrip.com.br\/wp-content\/uploads\/2022\/05\/pecan-pie-768x512.jpg 768w, https:\/\/wenttrip.com.br\/wp-content\/uploads\/2022\/05\/pecan-pie-389x259.jpg 389w\" sizes=\"(max-width: 651px) 100vw, 651px\" \/><\/figure>\n\n\n\n<p>The state is also famous for fighting for racial equality: <strong>black and white<\/strong>, it was here that the <strong>Dr. Martin Luther King Jr<\/strong>?? he made his speeches, organized the movements to march and left his historic mark.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\"><span class=\"ez-toc-section\" id=\"Pontos_turisticos_de_Alabama\"><\/span><strong>Alabama tourist attractions<\/strong><span class=\"ez-toc-section-end\"><\/span><\/h2>\n\n\n\n<p><strong>The state of Alabama has:<\/strong><\/p>\n\n\n\n<ul class=\"wp-block-list\"><li>24 State Parks<\/li><li>3 State Forests<\/li><li>4 State Wild Fauna Management Areas<\/li><li>4 National Forests<\/li><li>2 National Historic Sites<\/li><li>2 National Monuments<\/li><li>10 National Wildlife Refuge<\/li><\/ul>\n\n\n\n<p>Below, I will list the most popular tourist attractions.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\"><span class=\"ez-toc-section\" id=\"US_Space_Rocket_Center\"><\/span><strong>US Space &amp; Rocket Center<\/strong><span class=\"ez-toc-section-end\"><\/span><\/h3>\n\n\n\n<p>Located in Huntsville, it is a fantastic museum for science lovers, in this case Space Science.<\/p>\n\n\n\n<p>They are beautiful rockets, artifacts and space conquests.<\/p>\n\n\n\n<p>The museum opened in 1970, shortly after the landing of the <strong>Apollo 12<\/strong> on the moon.<\/p>\n\n\n\n<p>It is possible to interact with various exhibitions, has the exhibition of space shuttles, rockets and aircraft.<\/p>\n\n\n\n<div class=\"wp-block-columns is-layout-flex wp-container-core-columns-is-layout-9d6595d7 wp-block-columns-is-layout-flex\">\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\">\n<figure class=\"wp-block-image size-full\"><img decoding=\"async\" width=\"900\" height=\"723\" src=\"https:\/\/wenttrip.com.br\/wp-content\/uploads\/2022\/05\/NASM-A19740499000_DSH11.jpg\" alt=\"Command Module, Apollo 16 \" class=\"wp-image-4211\" srcset=\"https:\/\/wenttrip.com.br\/wp-content\/uploads\/2022\/05\/NASM-A19740499000_DSH11.jpg 900w, https:\/\/wenttrip.com.br\/wp-content\/uploads\/2022\/05\/NASM-A19740499000_DSH11-300x241.jpg 300w, https:\/\/wenttrip.com.br\/wp-content\/uploads\/2022\/05\/NASM-A19740499000_DSH11-768x617.jpg 768w, https:\/\/wenttrip.com.br\/wp-content\/uploads\/2022\/05\/NASM-A19740499000_DSH11-373x300.jpg 373w, https:\/\/wenttrip.com.br\/wp-content\/uploads\/2022\/05\/NASM-A19740499000_DSH11-310x250.jpg 310w\" sizes=\"(max-width: 900px) 100vw, 900px\" \/><figcaption>Command Module, Apollo 16 <\/figcaption><\/figure>\n<\/div>\n\n\n\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\">\n<figure class=\"wp-block-image size-full\"><img decoding=\"async\" width=\"900\" height=\"680\" src=\"https:\/\/wenttrip.com.br\/wp-content\/uploads\/2022\/05\/Rocket-City-1.webp\" alt=\"rockets\" class=\"wp-image-4212\" srcset=\"https:\/\/wenttrip.com.br\/wp-content\/uploads\/2022\/05\/Rocket-City-1.webp 900w, https:\/\/wenttrip.com.br\/wp-content\/uploads\/2022\/05\/Rocket-City-1-300x227.webp 300w, https:\/\/wenttrip.com.br\/wp-content\/uploads\/2022\/05\/Rocket-City-1-768x580.webp 768w, https:\/\/wenttrip.com.br\/wp-content\/uploads\/2022\/05\/Rocket-City-1-389x294.webp 389w\" sizes=\"(max-width: 900px) 100vw, 900px\" \/><\/figure>\n<\/div>\n<\/div>\n\n\n\n<p>In addition, there is the possibility to camp on site to learn more about space flight and aviation, learn about and use space simulators and various survival exercises.<\/p>\n\n\n\n<p>The experience is unique! &nbsp;&nbsp;<\/p>\n\n\n\n<p>Some of the items on display:<\/p>\n\n\n\n<ul class=\"wp-block-list\"><li>The Apollo 16 capsule, it orbited the Moon 64 times in 1972.<\/li><li>F1 rocket engine. With 5.6 meters high and 6,700,000N of thrust.<\/li><li>Saturn I Rocket<\/li><li>Rocket Jupiter IRBM, among others.<\/li><\/ul>\n\n\n\n<h3 class=\"wp-block-heading\"><span class=\"ez-toc-section\" id=\"Reserva_Nacional_Little_River_Canyon\"><\/span><strong>Little River Canyon National Reserve<\/strong><span class=\"ez-toc-section-end\"><\/span><\/h3>\n\n\n\n<p>Located at the top of Lookout Mountain, it comprises an area of 6 hectares that protects the longest river in the country: <strong>Little River.<\/strong><\/p>\n\n\n\n<div class=\"wp-block-columns is-layout-flex wp-container-core-columns-is-layout-9d6595d7 wp-block-columns-is-layout-flex\">\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\">\n<figure class=\"wp-block-image size-large\"><img decoding=\"async\" width=\"1024\" height=\"768\" src=\"https:\/\/wenttrip.com.br\/wp-content\/uploads\/2022\/05\/vgdijldqve940vawvoju-1024x768.jpg\" alt=\"Little River Canyon National Reserve\" class=\"wp-image-4213\" srcset=\"https:\/\/wenttrip.com.br\/wp-content\/uploads\/2022\/05\/vgdijldqve940vawvoju-1024x768.jpg 1024w, https:\/\/wenttrip.com.br\/wp-content\/uploads\/2022\/05\/vgdijldqve940vawvoju-300x225.jpg 300w, https:\/\/wenttrip.com.br\/wp-content\/uploads\/2022\/05\/vgdijldqve940vawvoju-768x576.jpg 768w, https:\/\/wenttrip.com.br\/wp-content\/uploads\/2022\/05\/vgdijldqve940vawvoju-389x292.jpg 389w, https:\/\/wenttrip.com.br\/wp-content\/uploads\/2022\/05\/vgdijldqve940vawvoju.jpg 1044w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n<\/div>\n\n\n\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\">\n<figure class=\"wp-block-image size-full\"><img decoding=\"async\" width=\"700\" height=\"525\" src=\"https:\/\/wenttrip.com.br\/wp-content\/uploads\/2022\/05\/469126705_472dece624_o-700x525-1.jpg\" alt=\"Little River Canyon National Reserve\" class=\"wp-image-4214\" srcset=\"https:\/\/wenttrip.com.br\/wp-content\/uploads\/2022\/05\/469126705_472dece624_o-700x525-1.jpg 700w, https:\/\/wenttrip.com.br\/wp-content\/uploads\/2022\/05\/469126705_472dece624_o-700x525-1-300x225.jpg 300w, https:\/\/wenttrip.com.br\/wp-content\/uploads\/2022\/05\/469126705_472dece624_o-700x525-1-389x292.jpg 389w\" sizes=\"(max-width: 700px) 100vw, 700px\" \/><\/figure>\n<\/div>\n<\/div>\n\n\n\n<p>It is possible to walk along trails, see waterfalls, see beautiful cliffs, walk along the edges of canyons, go climbing, abseiling, canoeing, cycling, swimming in the river and enjoying the beautiful landscape.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\"><span class=\"ez-toc-section\" id=\"Parque_Estadual_DeSoto\"><\/span><strong>DeSoto State Park<\/strong><span class=\"ez-toc-section-end\"><\/span><\/h3>\n\n\n\n<div class=\"wp-block-columns is-layout-flex wp-container-core-columns-is-layout-9d6595d7 wp-block-columns-is-layout-flex\">\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\">\n<figure class=\"wp-block-image size-full\"><img decoding=\"async\" width=\"960\" height=\"639\" src=\"https:\/\/wenttrip.com.br\/wp-content\/uploads\/2022\/05\/desotowestforklittleriver.jpg\" alt=\"Soto State Park\" class=\"wp-image-4215\" srcset=\"https:\/\/wenttrip.com.br\/wp-content\/uploads\/2022\/05\/desotowestforklittleriver.jpg 960w, https:\/\/wenttrip.com.br\/wp-content\/uploads\/2022\/05\/desotowestforklittleriver-300x200.jpg 300w, https:\/\/wenttrip.com.br\/wp-content\/uploads\/2022\/05\/desotowestforklittleriver-768x511.jpg 768w, https:\/\/wenttrip.com.br\/wp-content\/uploads\/2022\/05\/desotowestforklittleriver-389x259.jpg 389w\" sizes=\"(max-width: 960px) 100vw, 960px\" \/><\/figure>\n<\/div>\n\n\n\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\">\n<figure class=\"wp-block-image size-full\"><img decoding=\"async\" width=\"550\" height=\"367\" src=\"https:\/\/wenttrip.com.br\/wp-content\/uploads\/2022\/05\/desoto-state-park-desoto.jpg\" alt=\"Soto State Park\" class=\"wp-image-4216\" srcset=\"https:\/\/wenttrip.com.br\/wp-content\/uploads\/2022\/05\/desoto-state-park-desoto.jpg 550w, https:\/\/wenttrip.com.br\/wp-content\/uploads\/2022\/05\/desoto-state-park-desoto-300x200.jpg 300w, https:\/\/wenttrip.com.br\/wp-content\/uploads\/2022\/05\/desoto-state-park-desoto-389x260.jpg 389w\" sizes=\"(max-width: 550px) 100vw, 550px\" \/><\/figure>\n<\/div>\n<\/div>\n\n\n\n<p>Located on Lookout Mountain, eight miles northeast of Fort Payne.<\/p>\n\n\n\n<p>You will discover beautiful waterfalls, rivers, lots of forest, a picnic area with a playground and the best part: you can camp in the park!<\/p>\n\n\n\n<p>In addition, it is possible to fish, swim in an Olympic-sized swimming pool, bike and enjoy the beautiful attractions of the park such as the Sallie Howard Memorial Chapel and the Soto Falls.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\"><span class=\"ez-toc-section\" id=\"Monumento_Nacional_Freedom_Riders\"><\/span><strong>Freedom Riders National Monument<\/strong><span class=\"ez-toc-section-end\"><\/span><\/h3>\n\n\n\n<figure class=\"wp-block-image size-large is-resized\"><img decoding=\"async\" src=\"https:\/\/wenttrip.com.br\/wp-content\/uploads\/2022\/05\/AL_Anniston_FreedomRidersNM-1024x683.jpg\" alt=\"\" class=\"wp-image-4217\" width=\"730\" height=\"487\" srcset=\"https:\/\/wenttrip.com.br\/wp-content\/uploads\/2022\/05\/AL_Anniston_FreedomRidersNM-1024x683.jpg 1024w, https:\/\/wenttrip.com.br\/wp-content\/uploads\/2022\/05\/AL_Anniston_FreedomRidersNM-300x200.jpg 300w, https:\/\/wenttrip.com.br\/wp-content\/uploads\/2022\/05\/AL_Anniston_FreedomRidersNM-768x512.jpg 768w, https:\/\/wenttrip.com.br\/wp-content\/uploads\/2022\/05\/AL_Anniston_FreedomRidersNM-1536x1024.jpg 1536w, https:\/\/wenttrip.com.br\/wp-content\/uploads\/2022\/05\/AL_Anniston_FreedomRidersNM-389x259.jpg 389w, https:\/\/wenttrip.com.br\/wp-content\/uploads\/2022\/05\/AL_Anniston_FreedomRidersNM.jpg 1920w\" sizes=\"(max-width: 730px) 100vw, 730px\" \/><\/figure>\n\n\n\n<p>Created in 2017 by former President Barack Obama to preserve and commemorate the Freedom Riders.<\/p>\n\n\n\n<p>They formed the White and African American Civil Rights Movement, wanting equal rights in which there could be no separation of races in interstate travel.<\/p>\n\n\n\n<p>They took bus trips across the southern US in 1961, protesting segregated bus terminals.<\/p>\n\n\n\n<p>One day, people against the movement attacked the bus, the Riders managed to get out and were attacked by people on the street.<\/p>\n\n\n\n<p>This was the pivotal moment! And for this reason this monument was created.<\/p>\n\n\n\n<p>Monument Address: 1031 Gurnee Avenue Anniston, 36201.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\"><span class=\"ez-toc-section\" id=\"Riverfront_Park\"><\/span><strong>Riverfront Park<\/strong><span class=\"ez-toc-section-end\"><\/span><\/h3>\n\n\n\n<div class=\"wp-block-columns is-layout-flex wp-container-core-columns-is-layout-9d6595d7 wp-block-columns-is-layout-flex\">\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\">\n<figure class=\"wp-block-image size-full\"><img decoding=\"async\" width=\"550\" height=\"412\" src=\"https:\/\/wenttrip.com.br\/wp-content\/uploads\/2022\/05\/riverfront-park.jpg\" alt=\"Riverfront Park\" class=\"wp-image-4218\" srcset=\"https:\/\/wenttrip.com.br\/wp-content\/uploads\/2022\/05\/riverfront-park.jpg 550w, https:\/\/wenttrip.com.br\/wp-content\/uploads\/2022\/05\/riverfront-park-300x225.jpg 300w, https:\/\/wenttrip.com.br\/wp-content\/uploads\/2022\/05\/riverfront-park-389x291.jpg 389w\" sizes=\"(max-width: 550px) 100vw, 550px\" \/><\/figure>\n<\/div>\n\n\n\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\">\n<figure class=\"wp-block-image size-large\"><img decoding=\"async\" width=\"1024\" height=\"560\" src=\"https:\/\/wenttrip.com.br\/wp-content\/uploads\/2022\/05\/IMG_4047_Web72DPI-1024x560.jpg\" alt=\"Alabama \u2013 United States of America\" class=\"wp-image-4219\" srcset=\"https:\/\/wenttrip.com.br\/wp-content\/uploads\/2022\/05\/IMG_4047_Web72DPI-1024x560.jpg 1024w, https:\/\/wenttrip.com.br\/wp-content\/uploads\/2022\/05\/IMG_4047_Web72DPI-300x164.jpg 300w, https:\/\/wenttrip.com.br\/wp-content\/uploads\/2022\/05\/IMG_4047_Web72DPI-768x420.jpg 768w, https:\/\/wenttrip.com.br\/wp-content\/uploads\/2022\/05\/IMG_4047_Web72DPI-389x213.jpg 389w, https:\/\/wenttrip.com.br\/wp-content\/uploads\/2022\/05\/IMG_4047_Web72DPI.jpg 1280w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n<\/div>\n<\/div>\n\n\n\n<p>The park with its beautiful boardwalk is on the banks of the Alabama River (Alabama River), located in downtown Montgomery.<\/p>\n\n\n\n<p>&nbsp;You can take an afternoon to have a picnic, or if you have kids they will love the splash pad, plus there are exhibitions and historic city landmarks.<\/p>\n\n\n\n<p>Moored next to an amphitheater is the Harriott II, a 19th-century boat turned restaurant and has live music.<\/p>\n\n\n\n<h4 class=\"wp-block-heading\"><span class=\"ez-toc-section\" id=\"Alabama_%E2%80%93_Estados_Unidos_das_Americas\"><\/span>Alabama \u2013 United States of America<span class=\"ez-toc-section-end\"><\/span><\/h4>\n\n\n\n<p>Finally, I hope you enjoyed the tips! Share with us your experiences!<\/p>\n\n\n\n<p>Enjoy and learn more at:<\/p>\n\n\n\n<p> <a href=\"https:\/\/wenttrip.com.br\/en\/tips\/compras\/walmart-usa\/\">Walmart USA<\/a><\/p>\n\n\n\n<p> <a href=\"https:\/\/wenttrip.com.br\/en\/united-states\/trivia-about-usa\/\">Facts about the USA<\/a><\/p>\n\n\n\n<p> <a href=\"https:\/\/wenttrip.com.br\/en\/tips\/what-to-wear-to-travel\/\">What to wear to travel<\/a><\/p>\n\n\n\n<p> <a href=\"https:\/\/wenttrip.com.br\/en\/tips\/the-best-applications-to-travel-the-world\/\">The best apps for traveling the world<\/a><\/p>\n\n\n\n<p> <a href=\"https:\/\/wenttrip.com.br\/en\/united-states\/florida\/orlando\/orlando-florida-usa\/\">Orlando Florida USA<\/a><\/p>","protected":false},"excerpt":{"rendered":"<p>Discover here in this post everything about Alabama \u2013 United States of America, packed with lots of history, culture, tourist attractions and fun. Curiosities about Alabama Considered the 30th largest state by area and the 24th most populous in the USA, it has around 5 million inhabitants. It is located in the southeast region of the country, its capital is\u2026&nbsp;<a href=\"https:\/\/wenttrip.com.br\/en\/united-states\/alabama\/alabama-united-states-of-americas\/\" rel=\"bookmark\">Read More \u00bb<span class=\"screen-reader-text\">Alabama \u2013 United States of America<\/span><\/a><\/p>","protected":false},"author":1,"featured_media":4206,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"neve_meta_sidebar":"","neve_meta_container":"","neve_meta_enable_content_width":"","neve_meta_content_width":0,"neve_meta_title_alignment":"","neve_meta_author_avatar":"","neve_post_elements_order":"","neve_meta_disable_header":"","neve_meta_disable_footer":"","neve_meta_disable_title":"","footnotes":""},"categories":[1718],"tags":[1296,1297,1298,1304,1303,1300,1302,1305,1299,1301],"class_list":["post-4205","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-alabama","tag-alabama-estados-unidos-das-americas","tag-curiosidades-sobre-alabama","tag-montgomery","tag-monumento-nacional-freedom-riders","tag-parque-estadual-desoto","tag-pontos-turisticos-de-alabama","tag-reserva-nacional-little-river-canyon","tag-riverfront-park","tag-sweet-home-alabama","tag-u-s-space-rocket-center"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Alabama \u2013 Estados Unidos das Am\u00e9ricas - WentTrip<\/title>\n<meta name=\"description\" content=\"Descubra aqui nesse post tudo sobre Alabama \u2013 Estados Unidos das Am\u00e9ricas, recheado de muita hist\u00f3ria, cultura, atra\u00e7\u00f5es tur\u00edsticas e ...\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/wenttrip.com.br\/en\/united-states\/alabama\/alabama-united-states-of-americas\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Alabama \u2013 Estados Unidos das Am\u00e9ricas - WentTrip\" \/>\n<meta property=\"og:description\" content=\"Descubra aqui nesse post tudo sobre Alabama \u2013 Estados Unidos das Am\u00e9ricas, recheado de muita hist\u00f3ria, cultura, atra\u00e7\u00f5es tur\u00edsticas e ...\" \/>\n<meta property=\"og:url\" content=\"https:\/\/wenttrip.com.br\/en\/united-states\/alabama\/alabama-united-states-of-americas\/\" \/>\n<meta property=\"og:site_name\" content=\"WentTrip\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/m.facebook.com\/profile.php\" \/>\n<meta property=\"article:author\" content=\"https:\/\/m.facebook.com\/profile.php\" \/>\n<meta property=\"article:published_time\" content=\"2022-05-03T12:21:49+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2022-07-11T11:15:11+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/wenttrip.com.br\/wp-content\/uploads\/2022\/05\/SweetHomeHero.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"640\" \/>\n\t<meta property=\"og:image:height\" content=\"480\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Fernanda Machado\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@https:\/\/twitter.com\/wenttrip\" \/>\n<meta name=\"twitter:site\" content=\"@wenttrip\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"Fernanda Machado\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"7 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/wenttrip.com.br\\\/en\\\/united-states\\\/alabama\\\/alabama-united-states-of-americas\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/wenttrip.com.br\\\/en\\\/united-states\\\/alabama\\\/alabama-united-states-of-americas\\\/\"},\"author\":{\"name\":\"Fernanda Machado\",\"@id\":\"https:\\\/\\\/wenttrip.com.br\\\/en\\\/#\\\/schema\\\/person\\\/c0ff87b449a960037fdd1b024842fcf9\"},\"headline\":\"Alabama \u2013 Estados Unidos das Am\u00e9ricas\",\"datePublished\":\"2022-05-03T12:21:49+00:00\",\"dateModified\":\"2022-07-11T11:15:11+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/wenttrip.com.br\\\/en\\\/united-states\\\/alabama\\\/alabama-united-states-of-americas\\\/\"},\"wordCount\":762,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/wenttrip.com.br\\\/en\\\/#\\\/schema\\\/person\\\/c0ff87b449a960037fdd1b024842fcf9\"},\"image\":{\"@id\":\"https:\\\/\\\/wenttrip.com.br\\\/en\\\/united-states\\\/alabama\\\/alabama-united-states-of-americas\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/wenttrip.com.br\\\/wp-content\\\/uploads\\\/2022\\\/05\\\/SweetHomeHero.jpg\",\"keywords\":[\"Alabama \u2013 Estados Unidos das Am\u00e9ricas\",\"Curiosidades sobre Alabama\",\"Montgomery\",\"Monumento Nacional Freedom Riders\",\"Parque Estadual deSoto\",\"Pontos tur\u00edsticos de Alabama\",\"Reserva Nacional Little River Canyon\",\"Riverfront Park\",\"Sweet Home Alabama\",\"U.S. Space &amp; Rocket Center\"],\"articleSection\":[\"Alabama\"],\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/wenttrip.com.br\\\/en\\\/united-states\\\/alabama\\\/alabama-united-states-of-americas\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/wenttrip.com.br\\\/en\\\/united-states\\\/alabama\\\/alabama-united-states-of-americas\\\/\",\"url\":\"https:\\\/\\\/wenttrip.com.br\\\/en\\\/united-states\\\/alabama\\\/alabama-united-states-of-americas\\\/\",\"name\":\"Alabama \u2013 Estados Unidos das Am\u00e9ricas - WentTrip\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/wenttrip.com.br\\\/en\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/wenttrip.com.br\\\/en\\\/united-states\\\/alabama\\\/alabama-united-states-of-americas\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/wenttrip.com.br\\\/en\\\/united-states\\\/alabama\\\/alabama-united-states-of-americas\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/wenttrip.com.br\\\/wp-content\\\/uploads\\\/2022\\\/05\\\/SweetHomeHero.jpg\",\"datePublished\":\"2022-05-03T12:21:49+00:00\",\"dateModified\":\"2022-07-11T11:15:11+00:00\",\"description\":\"Descubra aqui nesse post tudo sobre Alabama \u2013 Estados Unidos das Am\u00e9ricas, recheado de muita hist\u00f3ria, cultura, atra\u00e7\u00f5es tur\u00edsticas e ...\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/wenttrip.com.br\\\/en\\\/united-states\\\/alabama\\\/alabama-united-states-of-americas\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/wenttrip.com.br\\\/en\\\/united-states\\\/alabama\\\/alabama-united-states-of-americas\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/wenttrip.com.br\\\/en\\\/united-states\\\/alabama\\\/alabama-united-states-of-americas\\\/#primaryimage\",\"url\":\"https:\\\/\\\/wenttrip.com.br\\\/wp-content\\\/uploads\\\/2022\\\/05\\\/SweetHomeHero.jpg\",\"contentUrl\":\"https:\\\/\\\/wenttrip.com.br\\\/wp-content\\\/uploads\\\/2022\\\/05\\\/SweetHomeHero.jpg\",\"width\":640,\"height\":480},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/wenttrip.com.br\\\/en\\\/united-states\\\/alabama\\\/alabama-united-states-of-americas\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"In\u00edcio\",\"item\":\"https:\\\/\\\/wenttrip.com.br\\\/en\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Alabama \u2013 Estados Unidos das Am\u00e9ricas\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/wenttrip.com.br\\\/en\\\/#website\",\"url\":\"https:\\\/\\\/wenttrip.com.br\\\/en\\\/\",\"name\":\"WentTrip\",\"description\":\"O seu guia completo com muitas dicas de aventuras, lugares, alimenta\u00e7\u00e3o, hot\u00e9is.\",\"publisher\":{\"@id\":\"https:\\\/\\\/wenttrip.com.br\\\/en\\\/#\\\/schema\\\/person\\\/c0ff87b449a960037fdd1b024842fcf9\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/wenttrip.com.br\\\/en\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":[\"Person\",\"Organization\"],\"@id\":\"https:\\\/\\\/wenttrip.com.br\\\/en\\\/#\\\/schema\\\/person\\\/c0ff87b449a960037fdd1b024842fcf9\",\"name\":\"Fernanda Machado\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/wenttrip.com.br\\\/wp-content\\\/uploads\\\/2022\\\/08\\\/WentTrip-2.png\",\"url\":\"https:\\\/\\\/wenttrip.com.br\\\/wp-content\\\/uploads\\\/2022\\\/08\\\/WentTrip-2.png\",\"contentUrl\":\"https:\\\/\\\/wenttrip.com.br\\\/wp-content\\\/uploads\\\/2022\\\/08\\\/WentTrip-2.png\",\"width\":1000,\"height\":1000,\"caption\":\"Fernanda Machado\"},\"logo\":{\"@id\":\"https:\\\/\\\/wenttrip.com.br\\\/wp-content\\\/uploads\\\/2022\\\/08\\\/WentTrip-2.png\"},\"description\":\"Aprendi que a vida \u00e9 mais leve quando colocamos uma mochila nas costas junto com sonhos. Amo viajar! Tenho 34 anos, mam\u00e3e de 3 cachorros: A Pantufa, O mutley e o Mixuruca. Compartilhamos nossas experi\u00eancias por aqui, esperamos que gostem!\",\"sameAs\":[\"https:\\\/\\\/wenttrip.com.br\",\"https:\\\/\\\/m.facebook.com\\\/profile.php\",\"https:\\\/\\\/www.instagram.com\\\/wenttrip\\\/\",\"https:\\\/\\\/x.com\\\/https:\\\/\\\/twitter.com\\\/wenttrip\",\"https:\\\/\\\/www.youtube.com\\\/c\\\/WentTrip\\\/videos\"],\"url\":\"https:\\\/\\\/wenttrip.com.br\\\/en\\\/author\\\/admin\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Alabama \u2013 United States of America - WentTrip","description":"Find out here in this post all about Alabama \u2013 United States of America, full of history, culture, tourist attractions and ...","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/wenttrip.com.br\/en\/united-states\/alabama\/alabama-united-states-of-americas\/","og_locale":"en_US","og_type":"article","og_title":"Alabama \u2013 Estados Unidos das Am\u00e9ricas - WentTrip","og_description":"Descubra aqui nesse post tudo sobre Alabama \u2013 Estados Unidos das Am\u00e9ricas, recheado de muita hist\u00f3ria, cultura, atra\u00e7\u00f5es tur\u00edsticas e ...","og_url":"https:\/\/wenttrip.com.br\/en\/united-states\/alabama\/alabama-united-states-of-americas\/","og_site_name":"WentTrip","article_publisher":"https:\/\/m.facebook.com\/profile.php","article_author":"https:\/\/m.facebook.com\/profile.php","article_published_time":"2022-05-03T12:21:49+00:00","article_modified_time":"2022-07-11T11:15:11+00:00","og_image":[{"width":640,"height":480,"url":"https:\/\/wenttrip.com.br\/wp-content\/uploads\/2022\/05\/SweetHomeHero.jpg","type":"image\/jpeg"}],"author":"Fernanda Machado","twitter_card":"summary_large_image","twitter_creator":"@https:\/\/twitter.com\/wenttrip","twitter_site":"@wenttrip","twitter_misc":{"Written by":"Fernanda Machado","Est. reading time":"7 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/wenttrip.com.br\/en\/united-states\/alabama\/alabama-united-states-of-americas\/#article","isPartOf":{"@id":"https:\/\/wenttrip.com.br\/en\/united-states\/alabama\/alabama-united-states-of-americas\/"},"author":{"name":"Fernanda Machado","@id":"https:\/\/wenttrip.com.br\/en\/#\/schema\/person\/c0ff87b449a960037fdd1b024842fcf9"},"headline":"Alabama \u2013 Estados Unidos das Am\u00e9ricas","datePublished":"2022-05-03T12:21:49+00:00","dateModified":"2022-07-11T11:15:11+00:00","mainEntityOfPage":{"@id":"https:\/\/wenttrip.com.br\/en\/united-states\/alabama\/alabama-united-states-of-americas\/"},"wordCount":762,"commentCount":0,"publisher":{"@id":"https:\/\/wenttrip.com.br\/en\/#\/schema\/person\/c0ff87b449a960037fdd1b024842fcf9"},"image":{"@id":"https:\/\/wenttrip.com.br\/en\/united-states\/alabama\/alabama-united-states-of-americas\/#primaryimage"},"thumbnailUrl":"https:\/\/wenttrip.com.br\/wp-content\/uploads\/2022\/05\/SweetHomeHero.jpg","keywords":["Alabama \u2013 Estados Unidos das Am\u00e9ricas","Curiosidades sobre Alabama","Montgomery","Monumento Nacional Freedom Riders","Parque Estadual deSoto","Pontos tur\u00edsticos de Alabama","Reserva Nacional Little River Canyon","Riverfront Park","Sweet Home Alabama","U.S. Space &amp; Rocket Center"],"articleSection":["Alabama"],"inLanguage":"en-US","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/wenttrip.com.br\/en\/united-states\/alabama\/alabama-united-states-of-americas\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/wenttrip.com.br\/en\/united-states\/alabama\/alabama-united-states-of-americas\/","url":"https:\/\/wenttrip.com.br\/en\/united-states\/alabama\/alabama-united-states-of-americas\/","name":"Alabama \u2013 United States of America - WentTrip","isPartOf":{"@id":"https:\/\/wenttrip.com.br\/en\/#website"},"primaryImageOfPage":{"@id":"https:\/\/wenttrip.com.br\/en\/united-states\/alabama\/alabama-united-states-of-americas\/#primaryimage"},"image":{"@id":"https:\/\/wenttrip.com.br\/en\/united-states\/alabama\/alabama-united-states-of-americas\/#primaryimage"},"thumbnailUrl":"https:\/\/wenttrip.com.br\/wp-content\/uploads\/2022\/05\/SweetHomeHero.jpg","datePublished":"2022-05-03T12:21:49+00:00","dateModified":"2022-07-11T11:15:11+00:00","description":"Find out here in this post all about Alabama \u2013 United States of America, full of history, culture, tourist attractions and ...","breadcrumb":{"@id":"https:\/\/wenttrip.com.br\/en\/united-states\/alabama\/alabama-united-states-of-americas\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/wenttrip.com.br\/en\/united-states\/alabama\/alabama-united-states-of-americas\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/wenttrip.com.br\/en\/united-states\/alabama\/alabama-united-states-of-americas\/#primaryimage","url":"https:\/\/wenttrip.com.br\/wp-content\/uploads\/2022\/05\/SweetHomeHero.jpg","contentUrl":"https:\/\/wenttrip.com.br\/wp-content\/uploads\/2022\/05\/SweetHomeHero.jpg","width":640,"height":480},{"@type":"BreadcrumbList","@id":"https:\/\/wenttrip.com.br\/en\/united-states\/alabama\/alabama-united-states-of-americas\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"In\u00edcio","item":"https:\/\/wenttrip.com.br\/en\/"},{"@type":"ListItem","position":2,"name":"Alabama \u2013 Estados Unidos das Am\u00e9ricas"}]},{"@type":"WebSite","@id":"https:\/\/wenttrip.com.br\/en\/#website","url":"https:\/\/wenttrip.com.br\/en\/","name":"WentTrip","description":"Your complete guide with lots of tips on adventures, places, food, hotels.","publisher":{"@id":"https:\/\/wenttrip.com.br\/en\/#\/schema\/person\/c0ff87b449a960037fdd1b024842fcf9"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/wenttrip.com.br\/en\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":["Person","Organization"],"@id":"https:\/\/wenttrip.com.br\/en\/#\/schema\/person\/c0ff87b449a960037fdd1b024842fcf9","name":"Fernanda Machado","image":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/wenttrip.com.br\/wp-content\/uploads\/2022\/08\/WentTrip-2.png","url":"https:\/\/wenttrip.com.br\/wp-content\/uploads\/2022\/08\/WentTrip-2.png","contentUrl":"https:\/\/wenttrip.com.br\/wp-content\/uploads\/2022\/08\/WentTrip-2.png","width":1000,"height":1000,"caption":"Fernanda Machado"},"logo":{"@id":"https:\/\/wenttrip.com.br\/wp-content\/uploads\/2022\/08\/WentTrip-2.png"},"description":"I learned that life is lighter when we put a backpack on our back along with dreams. I love to travel! I&#039;m 34 years old, mother of 3 dogs: Pantufa, Mutley and Mixuruca. We share our experiences here, we hope you like it!","sameAs":["https:\/\/wenttrip.com.br","https:\/\/m.facebook.com\/profile.php","https:\/\/www.instagram.com\/wenttrip\/","https:\/\/x.com\/https:\/\/twitter.com\/wenttrip","https:\/\/www.youtube.com\/c\/WentTrip\/videos"],"url":"https:\/\/wenttrip.com.br\/en\/author\/admin\/"}]}},"_links":{"self":[{"href":"https:\/\/wenttrip.com.br\/en\/wp-json\/wp\/v2\/posts\/4205","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/wenttrip.com.br\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/wenttrip.com.br\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/wenttrip.com.br\/en\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/wenttrip.com.br\/en\/wp-json\/wp\/v2\/comments?post=4205"}],"version-history":[{"count":0,"href":"https:\/\/wenttrip.com.br\/en\/wp-json\/wp\/v2\/posts\/4205\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/wenttrip.com.br\/en\/wp-json\/wp\/v2\/media\/4206"}],"wp:attachment":[{"href":"https:\/\/wenttrip.com.br\/en\/wp-json\/wp\/v2\/media?parent=4205"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/wenttrip.com.br\/en\/wp-json\/wp\/v2\/categories?post=4205"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/wenttrip.com.br\/en\/wp-json\/wp\/v2\/tags?post=4205"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}