{"id":135,"count":1,"description":"","link":"https:\/\/wenttrip.com.br\/de\/schild\/reisetipps-die-sie-wissen-mussen\/","name":"Reisetipps, die Sie kennen m\u00fcssen","slug":"dicas-de-viagens-que-voce-precisa-saber","taxonomy":"post_tag","meta":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Arquivo de Dicas de viagens que voc\u00ea precisa saber - WentTrip<\/title>\n<meta name=\"description\" content=\"Dicas de viagens que voc\u00ea precisa saber\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/wenttrip.com.br\/de\/schild\/reisetipps-die-sie-wissen-mussen\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Arquivo de Dicas de viagens que voc\u00ea precisa saber - WentTrip\" \/>\n<meta property=\"og:description\" content=\"Dicas de viagens que voc\u00ea precisa saber\" \/>\n<meta property=\"og:url\" content=\"https:\/\/wenttrip.com.br\/de\/schild\/reisetipps-die-sie-wissen-mussen\/\" \/>\n<meta property=\"og:site_name\" content=\"WentTrip\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:site\" content=\"@wenttrip\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"CollectionPage\",\"@id\":\"https:\\\/\\\/wenttrip.com.br\\\/de\\\/schild\\\/reisetipps-die-sie-wissen-mussen\\\/\",\"url\":\"https:\\\/\\\/wenttrip.com.br\\\/de\\\/schild\\\/reisetipps-die-sie-wissen-mussen\\\/\",\"name\":\"Arquivo de Dicas de viagens que voc\u00ea precisa saber - WentTrip\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/wenttrip.com.br\\\/de\\\/#website\"},\"description\":\"Dicas de viagens que voc\u00ea precisa saber\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/wenttrip.com.br\\\/de\\\/schild\\\/reisetipps-die-sie-wissen-mussen\\\/#breadcrumb\"},\"inLanguage\":\"de\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/wenttrip.com.br\\\/de\\\/schild\\\/reisetipps-die-sie-wissen-mussen\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"In\u00edcio\",\"item\":\"https:\\\/\\\/wenttrip.com.br\\\/de\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Dicas de viagens que voc\u00ea precisa saber\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/wenttrip.com.br\\\/de\\\/#website\",\"url\":\"https:\\\/\\\/wenttrip.com.br\\\/de\\\/\",\"name\":\"WentTrip\",\"description\":\"O seu guia completo com muitas dicas de aventuras, lugares, alimenta\u00e7\u00e3o, hot\u00e9is.\",\"publisher\":{\"@id\":\"https:\\\/\\\/wenttrip.com.br\\\/de\\\/#\\\/schema\\\/person\\\/c0ff87b449a960037fdd1b024842fcf9\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/wenttrip.com.br\\\/de\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de\"},{\"@type\":[\"Person\",\"Organization\"],\"@id\":\"https:\\\/\\\/wenttrip.com.br\\\/de\\\/#\\\/schema\\\/person\\\/c0ff87b449a960037fdd1b024842fcf9\",\"name\":\"Fernanda Machado\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/wenttrip.com.br\\\/wp-content\\\/uploads\\\/2022\\\/08\\\/WentTrip-2.png\",\"url\":\"https:\\\/\\\/wenttrip.com.br\\\/wp-content\\\/uploads\\\/2022\\\/08\\\/WentTrip-2.png\",\"contentUrl\":\"https:\\\/\\\/wenttrip.com.br\\\/wp-content\\\/uploads\\\/2022\\\/08\\\/WentTrip-2.png\",\"width\":1000,\"height\":1000,\"caption\":\"Fernanda Machado\"},\"logo\":{\"@id\":\"https:\\\/\\\/wenttrip.com.br\\\/wp-content\\\/uploads\\\/2022\\\/08\\\/WentTrip-2.png\"},\"description\":\"Aprendi que a vida \u00e9 mais leve quando colocamos uma mochila nas costas junto com sonhos. Amo viajar! Tenho 34 anos, mam\u00e3e de 3 cachorros: A Pantufa, O mutley e o Mixuruca. Compartilhamos nossas experi\u00eancias por aqui, esperamos que gostem!\",\"sameAs\":[\"https:\\\/\\\/wenttrip.com.br\",\"https:\\\/\\\/m.facebook.com\\\/profile.php\",\"https:\\\/\\\/www.instagram.com\\\/wenttrip\\\/\",\"https:\\\/\\\/x.com\\\/https:\\\/\\\/twitter.com\\\/wenttrip\",\"https:\\\/\\\/www.youtube.com\\\/c\\\/WentTrip\\\/videos\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Arquivo de Dicas de viagens que voc\u00ea precisa saber - WentTrip","description":"Reisetipps, die Sie kennen m\u00fcssen","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/wenttrip.com.br\/de\/schild\/reisetipps-die-sie-wissen-mussen\/","og_locale":"de_DE","og_type":"article","og_title":"Arquivo de Dicas de viagens que voc\u00ea precisa saber - WentTrip","og_description":"Dicas de viagens que voc\u00ea precisa saber","og_url":"https:\/\/wenttrip.com.br\/de\/schild\/reisetipps-die-sie-wissen-mussen\/","og_site_name":"WentTrip","twitter_card":"summary_large_image","twitter_site":"@wenttrip","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"CollectionPage","@id":"https:\/\/wenttrip.com.br\/de\/schild\/reisetipps-die-sie-wissen-mussen\/","url":"https:\/\/wenttrip.com.br\/de\/schild\/reisetipps-die-sie-wissen-mussen\/","name":"Archiv der Reisetipps, die Sie wissen m\u00fcssen \u2013 WentTrip","isPartOf":{"@id":"https:\/\/wenttrip.com.br\/de\/#website"},"description":"Reisetipps, die Sie kennen m\u00fcssen","breadcrumb":{"@id":"https:\/\/wenttrip.com.br\/de\/schild\/reisetipps-die-sie-wissen-mussen\/#breadcrumb"},"inLanguage":"de"},{"@type":"BreadcrumbList","@id":"https:\/\/wenttrip.com.br\/de\/schild\/reisetipps-die-sie-wissen-mussen\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"In\u00edcio","item":"https:\/\/wenttrip.com.br\/de\/"},{"@type":"ListItem","position":2,"name":"Dicas de viagens que voc\u00ea precisa saber"}]},{"@type":"WebSite","@id":"https:\/\/wenttrip.com.br\/de\/#website","url":"https:\/\/wenttrip.com.br\/de\/","name":"WentTrip","description":"Ihr kompletter Reisef\u00fchrer mit vielen Tipps zu Abenteuern, Orten, Essen, Hotels.","publisher":{"@id":"https:\/\/wenttrip.com.br\/de\/#\/schema\/person\/c0ff87b449a960037fdd1b024842fcf9"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/wenttrip.com.br\/de\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"},{"@type":["Person","Organization"],"@id":"https:\/\/wenttrip.com.br\/de\/#\/schema\/person\/c0ff87b449a960037fdd1b024842fcf9","name":"Fernanda Machado","image":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/wenttrip.com.br\/wp-content\/uploads\/2022\/08\/WentTrip-2.png","url":"https:\/\/wenttrip.com.br\/wp-content\/uploads\/2022\/08\/WentTrip-2.png","contentUrl":"https:\/\/wenttrip.com.br\/wp-content\/uploads\/2022\/08\/WentTrip-2.png","width":1000,"height":1000,"caption":"Fernanda Machado"},"logo":{"@id":"https:\/\/wenttrip.com.br\/wp-content\/uploads\/2022\/08\/WentTrip-2.png"},"description":"Ich habe gelernt, dass das Leben leichter ist, wenn wir neben Tr\u00e4umen auch einen Rucksack auf den R\u00fccken packen. Ich liebe es zu reisen! Ich bin 34 Jahre alt, Mutter von 3 Hunden: Pantufa, Mutley und Mixuruca. Wir teilen hier unsere Erfahrungen, wir hoffen, dass es euch gef\u00e4llt!","sameAs":["https:\/\/wenttrip.com.br","https:\/\/m.facebook.com\/profile.php","https:\/\/www.instagram.com\/wenttrip\/","https:\/\/x.com\/https:\/\/twitter.com\/wenttrip","https:\/\/www.youtube.com\/c\/WentTrip\/videos"]}]}},"_links":{"self":[{"href":"https:\/\/wenttrip.com.br\/de\/wp-json\/wp\/v2\/tags\/135","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/wenttrip.com.br\/de\/wp-json\/wp\/v2\/tags"}],"about":[{"href":"https:\/\/wenttrip.com.br\/de\/wp-json\/wp\/v2\/taxonomies\/post_tag"}],"wp:post_type":[{"href":"https:\/\/wenttrip.com.br\/de\/wp-json\/wp\/v2\/posts?tags=135"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}